{"id":15089,"date":"2025-01-10T14:27:12","date_gmt":"2025-01-10T14:27:12","guid":{"rendered":"https:\/\/scala.rzeszow.pl\/richiedi-un-preventivo-per-il-tuo-progetto\/"},"modified":"2025-07-22T22:23:04","modified_gmt":"2025-07-22T22:23:04","slug":"richiedi-un-preventivo-per-il-tuo-progetto","status":"publish","type":"page","link":"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/","title":{"rendered":"Richiedi un preventivo per il tuo progetto"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":5,"footnotes":""},"class_list":["post-15089","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v25.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Richiedi un preventivo per il tuo progetto - Producent SCALA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Richiedi un preventivo per il tuo progetto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/\" \/>\n<meta property=\"og:site_name\" content=\"Producent SCALA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ScalaBranding\/?fref=ts\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-22T22:23:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/\",\"url\":\"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/\",\"name\":\"Richiedi un preventivo per il tuo progetto - Producent SCALA\",\"isPartOf\":{\"@id\":\"https:\/\/scala.rzeszow.pl\/it\/#website\"},\"datePublished\":\"2025-01-10T14:27:12+00:00\",\"dateModified\":\"2025-07-22T22:23:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/scala.rzeszow.pl\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Richiedi un preventivo per il tuo progetto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/scala.rzeszow.pl\/it\/#website\",\"url\":\"https:\/\/scala.rzeszow.pl\/it\/\",\"name\":\"Scala\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/scala.rzeszow.pl\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/scala.rzeszow.pl\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/scala.rzeszow.pl\/it\/#organization\",\"name\":\"Scala\",\"url\":\"https:\/\/scala.rzeszow.pl\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/scala.rzeszow.pl\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/scala.rzeszow.pl\/wp-content\/uploads\/2024\/09\/logo-scala.svg\",\"contentUrl\":\"https:\/\/scala.rzeszow.pl\/wp-content\/uploads\/2024\/09\/logo-scala.svg\",\"width\":271,\"height\":67,\"caption\":\"Scala\"},\"image\":{\"@id\":\"https:\/\/scala.rzeszow.pl\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ScalaBranding\/?fref=ts\",\"https:\/\/www.linkedin.com\/company\/scalabranding\/\",\"https:\/\/www.instagram.com\/scala_branding\/\",\"https:\/\/www.youtube.com\/@scala_branding\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Richiedi un preventivo per il tuo progetto - Producent SCALA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/","og_locale":"it_IT","og_type":"article","og_title":"Richiedi un preventivo per il tuo progetto","og_url":"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/","og_site_name":"Producent SCALA","article_publisher":"https:\/\/www.facebook.com\/ScalaBranding\/?fref=ts","article_modified_time":"2025-07-22T22:23:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/","url":"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/","name":"Richiedi un preventivo per il tuo progetto - Producent SCALA","isPartOf":{"@id":"https:\/\/scala.rzeszow.pl\/it\/#website"},"datePublished":"2025-01-10T14:27:12+00:00","dateModified":"2025-07-22T22:23:04+00:00","breadcrumb":{"@id":"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/scala.rzeszow.pl\/it\/richiedi-un-preventivo-per-il-tuo-progetto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/scala.rzeszow.pl\/it\/"},{"@type":"ListItem","position":2,"name":"Richiedi un preventivo per il tuo progetto"}]},{"@type":"WebSite","@id":"https:\/\/scala.rzeszow.pl\/it\/#website","url":"https:\/\/scala.rzeszow.pl\/it\/","name":"Scala","description":"","publisher":{"@id":"https:\/\/scala.rzeszow.pl\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/scala.rzeszow.pl\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/scala.rzeszow.pl\/it\/#organization","name":"Scala","url":"https:\/\/scala.rzeszow.pl\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/scala.rzeszow.pl\/it\/#\/schema\/logo\/image\/","url":"https:\/\/scala.rzeszow.pl\/wp-content\/uploads\/2024\/09\/logo-scala.svg","contentUrl":"https:\/\/scala.rzeszow.pl\/wp-content\/uploads\/2024\/09\/logo-scala.svg","width":271,"height":67,"caption":"Scala"},"image":{"@id":"https:\/\/scala.rzeszow.pl\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ScalaBranding\/?fref=ts","https:\/\/www.linkedin.com\/company\/scalabranding\/","https:\/\/www.instagram.com\/scala_branding\/","https:\/\/www.youtube.com\/@scala_branding"]}]}},"_links":{"self":[{"href":"https:\/\/scala.rzeszow.pl\/it\/wp-json\/wp\/v2\/pages\/15089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scala.rzeszow.pl\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/scala.rzeszow.pl\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/scala.rzeszow.pl\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/scala.rzeszow.pl\/it\/wp-json\/wp\/v2\/comments?post=15089"}],"version-history":[{"count":1,"href":"https:\/\/scala.rzeszow.pl\/it\/wp-json\/wp\/v2\/pages\/15089\/revisions"}],"predecessor-version":[{"id":15091,"href":"https:\/\/scala.rzeszow.pl\/it\/wp-json\/wp\/v2\/pages\/15089\/revisions\/15091"}],"wp:attachment":[{"href":"https:\/\/scala.rzeszow.pl\/it\/wp-json\/wp\/v2\/media?parent=15089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}